{"id":1274,"count":3,"description":"","link":"http:\/\/store.manuelvazquezonline.com\/index.php\/category\/sportgun\/","name":"sportgun","slug":"sportgun","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"http:\/\/store.manuelvazquezonline.com\/index.php\/wp-json\/wp\/v2\/categories\/1274"}],"collection":[{"href":"http:\/\/store.manuelvazquezonline.com\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/store.manuelvazquezonline.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"http:\/\/store.manuelvazquezonline.com\/index.php\/wp-json\/wp\/v2\/posts?categories=1274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}