{"id":595,"count":1,"description":"","link":"http:\/\/store.manuelvazquezonline.com\/index.php\/category\/casinoonline05022\/","name":"casinoonline05022","slug":"casinoonline05022","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"http:\/\/store.manuelvazquezonline.com\/index.php\/wp-json\/wp\/v2\/categories\/595"}],"collection":[{"href":"http:\/\/store.manuelvazquezonline.com\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/store.manuelvazquezonline.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"http:\/\/store.manuelvazquezonline.com\/index.php\/wp-json\/wp\/v2\/posts?categories=595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}