{"id":799,"count":2,"description":"","link":"http:\/\/store.manuelvazquezonline.com\/index.php\/category\/1-xbeti18034\/","name":"1-xbeti18034","slug":"1-xbeti18034","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"http:\/\/store.manuelvazquezonline.com\/index.php\/wp-json\/wp\/v2\/categories\/799"}],"collection":[{"href":"http:\/\/store.manuelvazquezonline.com\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/store.manuelvazquezonline.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"http:\/\/store.manuelvazquezonline.com\/index.php\/wp-json\/wp\/v2\/posts?categories=799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}