{"id":801,"count":1,"description":"","link":"http:\/\/store.manuelvazquezonline.com\/index.php\/category\/casinoer18036\/","name":"Casinoer18036","slug":"casinoer18036","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"http:\/\/store.manuelvazquezonline.com\/index.php\/wp-json\/wp\/v2\/categories\/801"}],"collection":[{"href":"http:\/\/store.manuelvazquezonline.com\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/store.manuelvazquezonline.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"http:\/\/store.manuelvazquezonline.com\/index.php\/wp-json\/wp\/v2\/posts?categories=801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}